{"id":22537,"date":"2017-02-16T20:40:48","date_gmt":"2017-02-16T18:40:48","guid":{"rendered":"https:\/\/it.blogs.cam4.com\/files\/2017\/02\/acratta.jpg"},"modified":"2017-02-16T20:40:48","modified_gmt":"2017-02-16T18:40:48","slug":"acratta","status":"inherit","type":"attachment","link":"https:\/\/it.cam4.com\/blog\/scopri-le-foto-piu-hot-del-sexy-valentino-cam4-2017\/acratta\/","title":{"rendered":"acratta"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>acratta | Cam4 Blog Italiano | La migliore video-chat amatoriale web-cam gratis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"acratta | Cam4 Blog Italiano | La migliore video-chat amatoriale web-cam gratis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Cam4 Blog Italiano | La migliore video-chat amatoriale web-cam gratis\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cam4_it\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg\",\"url\":\"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg\",\"name\":\"acratta | Cam4 Blog Italiano | La migliore video-chat amatoriale web-cam gratis\",\"isPartOf\":{\"@id\":\"https:\/\/it.cam4.com\/blog\/#website\"},\"datePublished\":\"2017-02-16T18:40:48+00:00\",\"dateModified\":\"2017-02-16T18:40:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Scopri le foto pi\u00f9 HOT del Sexy Valentino CAM4 2017!\",\"item\":\"https:\/\/it.cam4.com\/blog\/scopri-le-foto-piu-hot-del-sexy-valentino-cam4-2017\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"acratta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/it.cam4.com\/blog\/#website\",\"url\":\"https:\/\/it.cam4.com\/blog\/\",\"name\":\"Cam4 Blog Italiano | La migliore video-chat amatoriale web-cam gratis\",\"description\":\"News sulla migliore video-chat sexy amatoriale | Ragazze,ragazzi,trans in web-cam coppie scambiste dal vivo gratis senza censura divertendosi e guadagnando\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/it.cam4.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"acratta | Cam4 Blog Italiano | La migliore video-chat amatoriale web-cam gratis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg","og_locale":"en_US","og_type":"article","og_title":"acratta | Cam4 Blog Italiano | La migliore video-chat amatoriale web-cam gratis","og_url":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg","og_site_name":"Cam4 Blog Italiano | La migliore video-chat amatoriale web-cam gratis","og_image":[{"width":1200,"height":675,"url":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@cam4_it","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg","url":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg","name":"acratta | Cam4 Blog Italiano | La migliore video-chat amatoriale web-cam gratis","isPartOf":{"@id":"https:\/\/it.cam4.com\/blog\/#website"},"datePublished":"2017-02-16T18:40:48+00:00","dateModified":"2017-02-16T18:40:48+00:00","breadcrumb":{"@id":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Scopri le foto pi\u00f9 HOT del Sexy Valentino CAM4 2017!","item":"https:\/\/it.cam4.com\/blog\/scopri-le-foto-piu-hot-del-sexy-valentino-cam4-2017\/"},{"@type":"ListItem","position":2,"name":"acratta"}]},{"@type":"WebSite","@id":"https:\/\/it.cam4.com\/blog\/#website","url":"https:\/\/it.cam4.com\/blog\/","name":"Cam4 Blog Italiano | La migliore video-chat amatoriale web-cam gratis","description":"News sulla migliore video-chat sexy amatoriale | Ragazze,ragazzi,trans in web-cam coppie scambiste dal vivo gratis senza censura divertendosi e guadagnando","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.cam4.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg'><img width=\"300\" height=\"169\" src=\"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta-300x169.jpg 300w, https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta-1024x576.jpg 1024w, https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta-600x338.jpg 600w, https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p class=\"attachment\"><a href='https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":675,"file":"2017\/02\/acratta.jpg","sizes":{"thumbnail":{"file":"acratta-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta-150x150.jpg"},"medium":{"file":"acratta-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta-300x169.jpg"},"large":{"file":"acratta-1024x576.jpg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta-1024x576.jpg"},"wysija-newsletters-max":{"file":"acratta-600x338.jpg","width":600,"height":338,"mime_type":"image\/jpeg","source_url":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta-600x338.jpg"},"full":{"file":"acratta.jpg","width":1200,"height":675,"mime_type":"image\/jpeg","source_url":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":22222,"source_url":"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2017\/02\/acratta.jpg","_links":{"self":[{"href":"https:\/\/it.cam4.com\/blog\/wp-json\/wp\/v2\/media\/22537"}],"collection":[{"href":"https:\/\/it.cam4.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/it.cam4.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/it.cam4.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/it.cam4.com\/blog\/wp-json\/wp\/v2\/comments?post=22537"}]}}